{"id":32,"date":"2024-05-08T22:43:14","date_gmt":"2024-05-08T22:43:14","guid":{"rendered":"https:\/\/entomologia.dili-up.com\/?p=32"},"modified":"2025-06-04T13:00:33","modified_gmt":"2025-06-04T13:00:33","slug":"diccionario-alfabetico-y-bilingue-espanol-ingles-de-ordenes-y-familias-de-insectos","status":"publish","type":"post","link":"https:\/\/entomologia.dili-up.com\/index.php\/2024\/05\/08\/diccionario-alfabetico-y-bilingue-espanol-ingles-de-ordenes-y-familias-de-insectos\/","title":{"rendered":"\u201cDiccionario alfab\u00e9tico y biling\u00fce (Espa\u00f1ol-Ingl\u00e9s) de \u00f3rdenes y familias de insectos\u201d"},"content":{"rendered":"\n<p class=\"has-text-align-center wp-block-paragraph\">&lt;<strong>En construcci\u00f3n<\/strong>&gt;<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">1: Orden <strong>COLEOPTERA<\/strong> \/ Order <strong>COLEOPTERA<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nota del administrador:<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify has-small-font-size wp-block-paragraph\">Iniciamos con esta primera entrada, el desarrollo de unos bloques de contenidos entomol\u00f3gicos que vamos a aplicar a los distintos \u00f3rdenes de insectos conocidos actualmente; con un enfoque biling\u00fce (<strong>espa\u00f1ol\/ingl\u00e9s<\/strong>) y alfab\u00e9ticamente, trataremos de recopilar la lista de familias incluidas en cada orden mostrando como es la equivalencia ling\u00fc\u00edstica en ambos idiomas. Los vocablos se\u00f1alados con la simbolog\u00eda <strong>[\ua66c]<\/strong> tendr\u00e1n entrada propia y si introducimos dicho t\u00e9rmino en nuestra \u201c<strong>CONSULTA DE ENTRADAS<\/strong>\u201c, se podr\u00e1 acceder a un contenido m\u00e1s extenso y detallado<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-A<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Acanthoceridae &#8211; V\u00e9ase <strong>Scarabaeidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Acanthocnemidae &#8211; V\u00e9ase <strong>Phloeophilidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Aculagnathidae<\/strong> [<em>Antsuking Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Aderidae <\/strong>[<em>Ant-like Leaf Beetle<\/em><strong>]<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Adimeridae &#8211; V\u00e9ase <strong>Colydiidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Aegialitidae &#8211; V\u00e9ase <strong>Salpingidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Aglycyderidae &#8211; V\u00e9ase <strong>Curculionidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Agyrtidae &#8211; V\u00e9ase Silphidae<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Alleculidae<\/strong> [<em>Comb-clawed Bark Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Allocorhynidae &#8211; V\u00e9ase <strong>Oxycorynidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Allocorynidae &#8211; V\u00e9ase <strong>Oxycorynidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Amphizoidae<\/strong> [<em>Trout-stream Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Anisotomidae &#8211; V\u00e9ase <strong>Leiodidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Anobiidae<\/strong> [<em>Drug-store Beetle<\/em>] and [<em>Death-watch Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Anthicidae<\/strong> [<em>Antlike Flower Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Anthribidae<\/strong> [<em>Fungus Weevil<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Apionidae [<em>Apionid weevils<\/em>] &#8211; V\u00e9ase <strong>Curculionidae<\/strong> (part)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Archeocrypticidae &#8211; V\u00e9ase <strong>Tenebrionidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Artematopidae &#8211; V\u00e9ase Dascilloidea<\/li>\n\n\n\n<li class=\"has-small-font-size\">Aspidiphoridae &#8211; V\u00e9ase <strong>Sphindidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Attelabidae [<em>Leaf-rolling weevils<\/em>] &#8211; V\u00e9ase <strong>Curculionidae<\/strong> (part)<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-B<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Belidae [<em>The New-York weevil<\/em>] &#8211; V\u00e9ase <strong>Ithyceridae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Biphyllidae<\/strong> [<em>False Skin Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Boganiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Boridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Bostrichidae<\/strong> [<em>Horned Powder-post Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Bostrychidae &#8211; V\u00e9ase <strong>Bostrichidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Brachypsectrida<\/strong>e [<em>Texas Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Brathinidae [<em>Grass-Root Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Brenthidae &#8211; V\u00e9ase <strong>Brentidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Brentidae <\/strong>[<em>Straight-snouted Weevil<\/em>] [<em>Primitive Weevils<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Bruchelidae &#8211; V\u00e9ase <strong>Anthribidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Bruchidae<\/strong> [<em>Pea Weevil<\/em>] and [<em>Bean Weevil<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Buprestidae<\/strong> [<em>Metallic Wood-boring Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Byrrhidae<\/strong> [<em>Pill Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Byturidae<\/strong> [<em>Fruitworm Beetle<\/em>]<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-C<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Callirhipidae<\/strong> [<em>Cedar Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Calyptomeridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cantharidae<\/strong> [<em>Soldier Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Carabidae<\/strong> [<em>Ground Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Catapochrotidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Catopidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cavognathidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cebrionida<\/strong>e [<em>Robust Click Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cephaloidae<\/strong> [<em>False Longhorned Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cerambycidae<\/strong> [<em>Longhorned Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ceratocanthidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cerophytidae<\/strong> [<em>Rare Click Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cerylonida<\/strong>e [<em>Minute Bark Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Chaetosomatidae &#8211; V\u00e9ase <strong>Cleridae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Chalcodryidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Chauliognathidae &#8211; V\u00e9ase <strong>Cantharidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Chelonariidae<\/strong> [<em>Turtle Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Choragidae &#8211; V\u00e9ase <strong>Anthribidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Chrysomelidae<\/strong> [<em>Leaf Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cicindelidae<\/strong> [<em>Tiger Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ciidae [<em>Minute Tree-fungus Beetle<\/em>] &#8211; V\u00e9ase <strong>Cisidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Cimberidae -V\u00e9ase <strong>Nemonychidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Cioidae &#8211; V\u00e9ase <strong>Cisidae<\/strong>\n<ul class=\"wp-block-list\">\n<li><strong>Cisidae <\/strong>[Minute Tree-fungus Beetle]<\/li>\n\n\n\n<li>Cistelidae V\u00e9ase <strong>Alleculidae<\/strong><\/li>\n<\/ul>\n<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Clambidae<\/strong> [<em>Minute Beetle<\/em>; <em>Fringe-winged Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Clavigeridae [<em>Ant-loving Beetle<\/em>] &#8211; V\u00e9ase <strong>Pselaphidae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Clerida<\/strong>e [<em>Checkered Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cneoglossidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Coccinellida<\/strong>e [<em>Ladybird Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Colydiidae<\/strong> [<em>Cylindrical Bark Betle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cononotidae &#8211; V\u00e9ase <strong>Salpingidae<\/strong> <\/li>\n\n\n\n<li class=\"has-small-font-size\">Corylophidae<strong> <\/strong>[<em>Minute Fungus Beetle<\/em>] &#8211; V\u00e9ase <strong>Orthoperidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Corynetidae -V\u00e9ase <strong>Cleridae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Cossyphodidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cryptophagidae<\/strong> [<em>Silken Fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cryptophilidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cucujidae<\/strong> [<em>Flat Bark Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Cupedidae<\/strong> [<em>Reticulated Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cupesidae &#8211; Ve\u00e1se <strong>Cupedidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Cupidae &#8211; V\u00e9ase <strong>Cupedidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Curculionidae<\/strong> [<em>Snout Beetle<\/em>] and [<em>True Weevil<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cyathoceridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Cyphonidae &#8211; V\u00e9ase <strong>Helodidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-D:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Dacoderidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Dascillida<\/strong>e [<em>Soft-bodied Plant Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Dasyceridae<\/strong> [<em>Minute Scavenger Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Dasytidae <\/strong>[<em>Soft-winged flower Beetle<\/em>] &#8211; V\u00e9ase <strong>Melyridae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Dermestidae<\/strong> [<em>Skin Beetle<\/em>; <em>Larder Beetle; Dermestid Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Derodontidae<\/strong> [<em>Tooth-necked Fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Diodyrhynchidae &#8211; V\u00e9ase <em>Nemonychidae<\/em><\/li>\n\n\n\n<li class=\"has-small-font-size\">Diphyllostomatidae -V\u00e9ase <strong>Lucanidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Discolomidae<\/strong> [<em>Tropical Long Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Disteniidae  &#8211; V\u00e9ase <strong>Cerambycidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Dorydirhynchidae &#8211; V\u00e9ase <strong>Nemonychidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Drilidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Dryopidae<\/strong> [<em>Long-toed Water Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Dytiscidae<\/strong> [<em>Predaceous Diving Beetle<\/em>]]<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-E:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Ectrephidae &#8211; V\u00e9ase <strong>Ptinidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Elacatidae &#8211; V\u00e9ase <strong>Othniidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Elateridae<\/strong> [<em>Click Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Elmidae<\/strong> [<em>Drive Beetle<\/em>] or [<em>Riffle Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Elminthidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Empelidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Endomychidae<\/strong> [<em>Handome Fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Erotylidae<\/strong> [<em>Pleasing Fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Eucinetidae<\/strong> [<em>Plate-thigh Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Eucnemidae<\/strong> [<em>False Click Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Euglenidae<\/strong> [<em>Antlike Leaf Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Eulichadidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Eurypogonidae &#8211; V\u00e9ase <strong>Dascillidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-text-align-left has-medium-font-size wp-block-paragraph\"><strong>-F:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Fulcidacidae &#8211; V\u00e9ase <strong>Chrysomelida<\/strong>e<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-G:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Georyssidae<\/strong> [<em>Mud-baked Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Geotrupidae &#8211; V\u00e9ase <strong>Scarabaeidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Glaphyridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Gnostidae &#8211; V\u00e9ase <strong>Ptinidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Gyrinidae<\/strong> [<em>Whirligig Beetle<\/em>]<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-H:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Haliplidae<\/strong> [<em>Crawling Water Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Helmidae &#8211; V\u00e9ase <strong>Elmidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Helodidae<\/strong> [<em>Marsh Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Helophoridae &#8211; V\u00e9ase <strong>Hydrophilidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Helopidae &#8211; V\u00e9ase <strong>Tenebrionidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Helotidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hemipeplidae &#8211; V\u00e9ase <strong>Cucujidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Heteroceridae<\/strong> [<em>Variegated Mud-loving Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Heterotarsidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Histeridae<\/strong> [<em>Clown Beetle<\/em>; <em>Hister Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hobartiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Homalisidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hybosoridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Hydraenidae<\/strong> [<em>Minute moss Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hydrochidae &#8211; V\u00e9ase <strong>Hydrophilidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Hydrophilidae<\/strong> [<em>Water Scavenger Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hydroporidae &#8211; V\u00e9ase <strong>Dytiscidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Hydroscaphidae<\/strong> [<em>Skiff Beetle<\/em>)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hydrobiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hyphydridae &#8211; V\u00e9ase <strong>Dytiscidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Hygrobiidae &#8211; V\u00e9ase <strong>Pelobiidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Hylophilidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Hypocephalidae &#8211; V\u00e9ase <strong>Cerambycidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Hyp0copridae &#8211; V\u00e9ase <strong>Rhizophagidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-I:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Inopeplidae &#8211; V\u00e9ase <strong>Cucujidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Ipidae &#8211; V\u00e9ase <strong>Scolytidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Ithyceridae &#8211; V\u00e9ase <strong>Curculionidae<\/strong> (part)<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-J:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Jacobsoniidae<\/strong> [<em>False Snout Beetle<\/em>]<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-K:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Karumiidae<\/strong> [<em>Termitelike Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Korynetidae &#8211; V\u00e9ase <strong>Cleridae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-L:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Laemophloeidae [V\u00e9ase Cucujidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lagriidae<\/strong> [<em>Long-jointed Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lamiidae [V\u00e9ase Cerambycidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lamingtoniidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lamprosomatidae [V\u00e9ase Chrysomelidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lampyridae<\/strong> [<em>Firefly Beetle<\/em>; <em>Fireflies<\/em>; <em>Lightningbugs<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Languriidae<\/strong> [<em>Lizard Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lariconbiidae [V\u00e9ase Derodontidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lariidae [V\u00e9ase Bruchidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lathridiidae<\/strong> <em>[Minute Brown Scavenger Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Latridiidae [V\u00e9ase Lathridiidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Latrochidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lebiidae [V\u00e9ase Carabidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Leiodidae<\/strong> [<em>Round Fungus Beetle<\/em>] &#8211; V\u00e9ase <strong>Silphidae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lepiceridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Leptinidae <\/strong>[<em>Mammal-Nest Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Leptodiridae<\/strong> [<em>Small Carrion Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lepturidae [V\u00e9ase Cerambycidae]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Limnebiidae<\/strong> [<em>Minute Moss Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Limnichidae<\/strong> [<em>Minute Marsh-loving Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Limniidae [V\u00e9ase Elmidae]                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                                             <\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Limulodidae<\/strong> [<em>Horseshoe Crab Beetle<\/em>] -V\u00e9ase <strong>Ptiliidae <\/strong>(part) y <strong>Staphylinidae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Liodidae &#8211; V\u00e9ase <strong>Leiodidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Lophocateridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lucanidae<\/strong> [<em>Stag Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ludiidae- V\u00e9ase <strong>Elateridae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Lutrochidae &#8211; V\u00e9ase <strong>Limnichidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lycidae <\/strong>[<em>Net-winged Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lyctidae <\/strong>[<em>Powder-post Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lymexylidae -V\u00e9ase <strong>Lymexylonidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Lymexylonidae <\/strong>[<em>Ship-timber Beetle<\/em>; <em>Timberworm Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Lytidae &#8211; V\u00e9ase <strong>Meloidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Lyttidae &#8211; V\u00e9ase <strong>Meloidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-M:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Malachiidae <\/strong>[<strong>Soft-winged flower Beetle<\/strong>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Megalopodidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Melandryidae<\/strong> [<em>False Darkling Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Melasidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Meloidae<\/strong> [<em>Blister Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Melyridae [<em>Soft-winged Flower Beetle<\/em>] -Ve\u00e1se <strong>Malachidae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Merophysiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Merycidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Micromalthidae<\/strong> [<em>Telephone-pole Beetle<\/em>; <em>Micromalthid Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Micropeplidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Microsporidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Monoedidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Monommatidae<\/strong> [<em>Opossum Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Monommidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Monotomidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Mordellidae<\/strong> [<em>Tumbling Flower Beetl<\/em>e]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Murmidiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Mycetaeidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Mycteridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Mycetophagidae<\/strong> [<em>Hairy Fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Mylabridae [<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-N:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Nemonychidae <\/strong>[Piner-flower snout Beetle] V\u00e9ase <strong>Curculionidae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Nilionidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Nitidulidae<\/strong> [<em>Sap-feeding Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Nosodendridae<\/strong> [<em>Wounded-tree Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Noteridae<\/strong> [<em>Burrowing Water Beetle<\/em>]<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-\u00d1:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">No constan<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-O:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Ochodaeidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Oedemeridae<\/strong> [<em>Pollen feeding Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Omethidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ommadidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ommatidae &#8211; V\u00e9ase <strong>Cupedidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Omophronidae [<em>Round Sand Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Orthoperidae <\/strong>[<em>Minute fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ostomatidae &#8211; V\u00e9ase <strong>Ostomidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Ostomidae <\/strong>[<em>Bark-gnawing Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Othniidae<\/strong> [<em>False Tiger Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Oxycorynidae <\/strong>[Oxycorynid weevils] &#8211; V\u00e9ase <strong>Curculionidae <\/strong>(part)<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-P:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Parnidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Passalidae <\/strong>[<em>Peg Beetle<\/em>] or [<em>Bess Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Passandridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Paussidae <\/strong>[<em>Ant nest Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Pedilidae<\/strong> [<em>False Antlike Flower Beetle<\/em>] or [<em>False antlwing flower Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Pelobiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Peltidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Perimylopidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Perothopidae<\/strong> [<em>Beech-tree Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Petriidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Phaenocephalidae<\/strong> [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Phalacridae<\/strong> [<em>Shining Flower Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Phengodidae<\/strong> [<em>Glowworm; Glow-worms; Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Phloeophilidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Phloeostichidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Phloiophilidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Phreatodytidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Phycosecidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Plastoceridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Platypodidae<\/strong> [<em>Ambrosia Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Platypsyllidae [<em>Beaver parasites<\/em>] &#8211; V\u00e9ase <strong>Leptinidae <\/strong>(part)<\/li>\n\n\n\n<li class=\"has-small-font-size\">Platyrrhinidae &#8211; V\u00e9ase <strong>Anthribidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Platystomidae &#8211; V\u00e9ase <strong>Anthribidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Pleocomidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Propalticidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Prostomidae<\/strong> [<em>Jugular-horned Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Proterhinidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Protocucujidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Pselaphidae <\/strong>[<em>Antloving Beetle<\/em>; <em>Short-winged mold Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Psephenidae<\/strong> [<em>Water Penny Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Pterogeniidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ptilidae &#8211; V\u00e9ase <strong>Ptiliidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Ptiliidae<\/strong> [<em>Feather-winged Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Ptilodactylidae<\/strong> [<em>Toed-winged Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Ptinidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Pyrochroidae<\/strong> [<em>Fire-colored Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Pythidae<\/strong> [<em>Spider Beetle<\/em>]<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-Q:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">No constan<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-R:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Rhinomaceridae- Ve\u00e1se <strong>Nemonychidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Rhipiceridae<\/strong> [<em>Cicada Parasite Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Rhipiphoridae [w<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Rhizophagidae <\/strong>[<em>Root-eating Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Rhychitidae<\/strong> [<em>Weedge-shaped Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Rhysodidae<\/strong> [<em>Wrinkled Bark Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Rhyssodidae &#8211; V\u00e9ase <strong>Rhysodidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-S:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Salpingidae<\/strong> [<em>Narrow-waisted Bark Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Sandalidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Sarothriidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Scaphidiidae<\/strong> [<em>Shining Fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Scarabaeidae<\/strong> [<em>Lamellicorn Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Scirtidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Scolytidae<\/strong> [<em>Bark Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Scraptiidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Scydmaenidae<\/strong> [<em>Antlike stone Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Serropalpidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Silphidae<\/strong> [<em>Carrion Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Silvanidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Sperchaeidae &#8211; V\u00e9ase <strong>Spercheidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Spercheidae <\/strong>[<em>Filterfeeding Water Scavenger Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Sphaeriidae<\/strong> [<em>Minute Bog Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Sphaeritidae<\/strong> [<em>False Clown Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Sphaerosomatidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Sphaerosomidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Sphindidae<\/strong> [<em>Dry-fungus Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Staphylinidae <\/strong>[<em>Rove Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Syncalpytidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Synchroidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Synteliidae [<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-T:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\"><strong>Telegeusidae <\/strong>[<em>Long-lipped Beetle<\/em>; <em>Telegeusid Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Telephoridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Temnochilidae &#8211; V\u00e9ase <strong>Ostomidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Tenebrionidae<\/strong> [<em>Darkling Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Tentyriidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Tetraphaleridae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Tetratomidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Thoricitidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\"><strong>Throscidae<\/strong> [<em>False Metallic Wood-boring Beetle<\/em>]<\/li>\n\n\n\n<li class=\"has-small-font-size\">Torridincolidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Trachypachidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Tretothoracidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Trichopterygidae &#8211; V\u00e9ase <strong>Ptiliidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Trictenotomidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Trogidae [<\/li>\n\n\n\n<li class=\"has-small-font-size\">Trogositidae &#8211; V\u00e9ase <strong>Ostomidae<\/strong><\/li>\n\n\n\n<li class=\"has-small-font-size\">Trogossitidae &#8211; V\u00e9ase <strong>Ostomidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-U:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Urodonidae &#8211; V\u00e9ase <strong>Bruchidae<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-V:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">No constan<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-X:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Xylophilidae [<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-Y:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">No constan<\/li>\n<\/ul>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\"><strong>-Z:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-small-font-size\">Zopheridae [<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&lt;En construcci\u00f3n&gt; 1: Orden COLEOPTERA \/ Order COLEOPTERA Nota del administrador: Iniciamos con esta primera entrada, el desarrollo de unos bloques de contenidos entomol\u00f3gicos que vamos a aplicar a los distintos \u00f3rdenes de insectos conocidos actualmente; con un enfoque biling\u00fce (espa\u00f1ol\/ingl\u00e9s) y alfab\u00e9ticamente, trataremos de recopilar la lista de familias incluidas en cada orden mostrando &hellip; <a href=\"https:\/\/entomologia.dili-up.com\/index.php\/2024\/05\/08\/diccionario-alfabetico-y-bilingue-espanol-ingles-de-ordenes-y-familias-de-insectos\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> \u00ab\u201cDiccionario alfab\u00e9tico y biling\u00fce (Espa\u00f1ol-Ingl\u00e9s) de \u00f3rdenes y familias de insectos\u201d\u00bb<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-32","post","type-post","status-publish","format-standard","hentry","category-nomenclatura-bilingue"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/posts\/32","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/comments?post=32"}],"version-history":[{"count":15,"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/posts\/32\/revisions"}],"predecessor-version":[{"id":110,"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/posts\/32\/revisions\/110"}],"wp:attachment":[{"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/media?parent=32"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/categories?post=32"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entomologia.dili-up.com\/index.php\/wp-json\/wp\/v2\/tags?post=32"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}